{"id":134063,"date":"2024-04-05T00:10:51","date_gmt":"2024-04-05T03:10:51","guid":{"rendered":"https:\/\/www.gaveanews.com\/?p=134063"},"modified":"2024-04-07T08:40:11","modified_gmt":"2024-04-07T11:40:11","slug":"flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria","status":"publish","type":"post","link":"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/","title":{"rendered":"Flamengo aceitar\u00e1 vender Fabr\u00edcio Bruno por quase metade da multa rescis\u00f3ria"},"content":{"rendered":"\n<p>Fabr\u00edcio Bruno, zagueiro do Flamengo, tornou-se um nome ainda mais importante no futebol ap\u00f3s ser convocado para a Sele\u00e7\u00e3o Brasileira. Esse destaque n\u00e3o s\u00f3 o valorizou como jogador mas tamb\u00e9m despertou o interesse de grandes clubes europeus. Segundo informa\u00e7\u00f5es o Flamengo estaria disposto a negociar o atleta por uma oferta na casa dos 18 milh\u00f5es de euros (aproximadamente R$ 98 milh\u00f5es), valor significativamente menor que sua cl\u00e1usula de rescis\u00e3o, estipulada em 30 milh\u00f5es de euros (cerca de R$ 162 milh\u00f5es).<\/p>\n\n\n\n<p>Durante a recente Data FIFA, Fabr\u00edcio Bruno foi pe\u00e7a-chave nos jogos contra Inglaterra e Espanha, demonstrando seu valor no cen\u00e1rio internacional. Seu retorno ao Brasil foi igualmente marcante, com participa\u00e7\u00f5es decisivas nas partidas contra Nova Igua\u00e7u e Millonarios, assegurando sua posi\u00e7\u00e3o como titular absoluto no Flamengo, mesmo com a chegada de L\u00e9o Ortiz, outro zagueiro de destaque vindo do Bragantino.<\/p>\n\n\n\n<p>Fabr\u00edcio chegou ao clube carioca no in\u00edcio de 2022 e teve um primeiro ano repleto de conquistas, incluindo t\u00edtulos da Copa do Brasil e da Copa Conmebol Libertadores. No entanto, foi em 2023, sob a orienta\u00e7\u00e3o do t\u00e9cnico portugu\u00eas Vitor Pereira, que ele realmente consolidou sua posi\u00e7\u00e3o como um titular indiscut\u00edvel, trazendo seguran\u00e7a e consist\u00eancia \u00e0 defesa rubro-negra.<\/p>\n\n\n\n<p>O pr\u00f3prio jogador, em uma demonstra\u00e7\u00e3o de humildade e comprometimento, se define como um &#8220;jogador de equipe&#8221;. Em suas palavras, a prioridade sempre \u00e9 a seguran\u00e7a defensiva, reconhecendo a capacidade ofensiva de seus companheiros tanto no Flamengo quanto na sele\u00e7\u00e3o:<\/p>\n\n\n\n<p><em>\u2014 Sempre priorizo a seguran\u00e7a. Tanto no clube (Flamengo) quanto na sele\u00e7\u00e3o, h\u00e1 jogadores ofensivos capazes de decidir partidas. Por isso, mantenho a responsabilidade em alta. Sou um jogador de equipe, jogo pelo coletivo, buscando defender ao m\u00e1ximo. Se n\u00e3o sofremos gols, sabemos que teremos chances de marcar e vencer o jogo<\/em>, afirmou o jogador.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-carros-no-gavea-news\">Carros no G\u00e1vea News<\/h2>\n\n\n\n<p>O portal G\u00e1vea News agora tamb\u00e9m est\u00e1 produzindo conte\u00fados relacionados ao setor automotivo. Se voc\u00ea deseja se manter bem informado sobre esse assunto,&nbsp;<a href=\"https:\/\/www.gaveanews.com\/index.php\/carros\/\">clique aqui para acessar exclusivamente as not\u00edcias dessa categoria.<\/a> Recentemente, publicamos duas not\u00edcias de destaque:&nbsp;<a href=\"https:\/\/www.gaveanews.com\/index.php\/2024\/03\/26\/completamente-reformulada-veja-fotos-da-nova-versao-da-hilux\/?utm_source=Recirculacao&amp;utm_medium=SubtituloFinalDaMateria&amp;utm_campaign=SubtituloFinalDaMateria\">Completamente reformulada! Veja fotos da nova vers\u00e3o da Hilux<\/a>, e a&nbsp;<a href=\"https:\/\/www.gaveanews.com\/index.php\/2024\/03\/12\/chevrolet-ira-lancar-2-carros-ineditos-no-brasil\/?utm_source=Recirculacao&amp;utm_medium=SubtituloFinalDaMateria&amp;utm_campaign=SubtituloFinalDaMateria\">Chevrolet ir\u00e1 lan\u00e7ar 2 carros in\u00e9ditos no Brasil (veja detalhes)<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fabr\u00edcio Bruno, zagueiro do Flamengo, tornou-se um nome ainda mais importante no futebol ap\u00f3s ser convocado para a Sele\u00e7\u00e3o Brasileira. Esse destaque n\u00e3o s\u00f3 o valorizou como jogador mas tamb\u00e9m despertou o interesse de grandes clubes europeus. Segundo informa\u00e7\u00f5es o Flamengo estaria disposto a negociar o atleta por uma oferta na casa dos 18 milh\u00f5es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":132585,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[186],"class_list":["post-134063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-flamengo","tag-fabricio-bruno-soares-de-faria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Flamengo aceitar\u00e1 vender Fabr\u00edcio Bruno por quase metade da multa rescis\u00f3ria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flamengo aceitar\u00e1 vender Fabr\u00edcio Bruno por quase metade da multa rescis\u00f3ria\" \/>\n<meta property=\"og:description\" content=\"Fabr\u00edcio Bruno, zagueiro do Flamengo, tornou-se um nome ainda mais importante no futebol ap\u00f3s ser convocado para a Sele\u00e7\u00e3o Brasileira. Esse destaque n\u00e3o s\u00f3 o valorizou como jogador mas tamb\u00e9m despertou o interesse de grandes clubes europeus. Segundo informa\u00e7\u00f5es o Flamengo estaria disposto a negociar o atleta por uma oferta na casa dos 18 milh\u00f5es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/\" \/>\n<meta property=\"og:site_name\" content=\"G\u00e1vea News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/gaveaNews\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-05T03:10:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-07T11:40:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/fabricio-bruno-selecao-brasileira.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipe G\u00e1vea News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe G\u00e1vea News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/\"},\"author\":{\"name\":\"Equipe G\u00e1vea News\",\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/2ec14f73fb96be2caf28f91afb14749d\"},\"headline\":\"Flamengo aceitar\u00e1 vender Fabr\u00edcio Bruno por quase metade da multa rescis\u00f3ria\",\"datePublished\":\"2024-04-05T03:10:51+00:00\",\"dateModified\":\"2024-04-07T11:40:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/\"},\"wordCount\":408,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/fabricio-bruno-selecao-brasileira.webp\",\"keywords\":[\"Fabr\u00edcio Bruno Soares de Faria\"],\"articleSection\":[\"Flamengo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.gaveanews.com\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/\",\"url\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/\",\"name\":\"Flamengo aceitar\u00e1 vender Fabr\u00edcio Bruno por quase metade da multa rescis\u00f3ria\",\"isPartOf\":{\"@id\":\"https:\/\/www.gaveanews.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/fabricio-bruno-selecao-brasileira.webp\",\"datePublished\":\"2024-04-05T03:10:51+00:00\",\"dateModified\":\"2024-04-07T11:40:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/2ec14f73fb96be2caf28f91afb14749d\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#primaryimage\",\"url\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/fabricio-bruno-selecao-brasileira.webp\",\"contentUrl\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/fabricio-bruno-selecao-brasileira.webp\",\"width\":1200,\"height\":800,\"caption\":\"Fabr\u00edcio Bruno em a\u00e7\u00e3o pela Sele\u00e7\u00e3o Brasileira (Foto: Reprodu\u00e7\u00e3o\/twitter\/@SofascoreBR)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.gaveanews.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flamengo aceitar\u00e1 vender Fabr\u00edcio Bruno por quase metade da multa rescis\u00f3ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gaveanews.com\/#website\",\"url\":\"https:\/\/www.gaveanews.com\/\",\"name\":\"G\u00e1vea News\",\"description\":\"Veja todas as not\u00edcias sobre o Flamengo: Contrata\u00e7\u00f5es, categorias de base, resultados das partidas, tabela de classifica\u00e7\u00e3o, pr\u00f3ximos jogos!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gaveanews.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/2ec14f73fb96be2caf28f91afb14749d\",\"name\":\"Equipe G\u00e1vea News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1e1956f1facbffd3f8fa53a326721950116b3b9dc9bd44939c01180fd4a745a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1e1956f1facbffd3f8fa53a326721950116b3b9dc9bd44939c01180fd4a745a9?s=96&d=mm&r=g\",\"caption\":\"Equipe G\u00e1vea News\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Flamengo aceitar\u00e1 vender Fabr\u00edcio Bruno por quase metade da multa rescis\u00f3ria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/","og_locale":"pt_BR","og_type":"article","og_title":"Flamengo aceitar\u00e1 vender Fabr\u00edcio Bruno por quase metade da multa rescis\u00f3ria","og_description":"Fabr\u00edcio Bruno, zagueiro do Flamengo, tornou-se um nome ainda mais importante no futebol ap\u00f3s ser convocado para a Sele\u00e7\u00e3o Brasileira. Esse destaque n\u00e3o s\u00f3 o valorizou como jogador mas tamb\u00e9m despertou o interesse de grandes clubes europeus. Segundo informa\u00e7\u00f5es o Flamengo estaria disposto a negociar o atleta por uma oferta na casa dos 18 milh\u00f5es [&hellip;]","og_url":"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/","og_site_name":"G\u00e1vea News","article_publisher":"https:\/\/facebook.com\/gaveaNews\/","article_published_time":"2024-04-05T03:10:51+00:00","article_modified_time":"2024-04-07T11:40:11+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/fabricio-bruno-selecao-brasileira.webp","type":"image\/webp"}],"author":"Equipe G\u00e1vea News","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipe G\u00e1vea News","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#article","isPartOf":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/"},"author":{"name":"Equipe G\u00e1vea News","@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/2ec14f73fb96be2caf28f91afb14749d"},"headline":"Flamengo aceitar\u00e1 vender Fabr\u00edcio Bruno por quase metade da multa rescis\u00f3ria","datePublished":"2024-04-05T03:10:51+00:00","dateModified":"2024-04-07T11:40:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/"},"wordCount":408,"commentCount":0,"image":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/fabricio-bruno-selecao-brasileira.webp","keywords":["Fabr\u00edcio Bruno Soares de Faria"],"articleSection":["Flamengo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.gaveanews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/","url":"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/","name":"Flamengo aceitar\u00e1 vender Fabr\u00edcio Bruno por quase metade da multa rescis\u00f3ria","isPartOf":{"@id":"https:\/\/www.gaveanews.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#primaryimage"},"image":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/fabricio-bruno-selecao-brasileira.webp","datePublished":"2024-04-05T03:10:51+00:00","dateModified":"2024-04-07T11:40:11+00:00","author":{"@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/2ec14f73fb96be2caf28f91afb14749d"},"breadcrumb":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#primaryimage","url":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/fabricio-bruno-selecao-brasileira.webp","contentUrl":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/fabricio-bruno-selecao-brasileira.webp","width":1200,"height":800,"caption":"Fabr\u00edcio Bruno em a\u00e7\u00e3o pela Sele\u00e7\u00e3o Brasileira (Foto: Reprodu\u00e7\u00e3o\/twitter\/@SofascoreBR)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/04\/05\/flamengo-aceitara-vender-fabricio-bruno-por-quase-metade-da-multa-rescisoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gaveanews.com\/"},{"@type":"ListItem","position":2,"name":"Flamengo aceitar\u00e1 vender Fabr\u00edcio Bruno por quase metade da multa rescis\u00f3ria"}]},{"@type":"WebSite","@id":"https:\/\/www.gaveanews.com\/#website","url":"https:\/\/www.gaveanews.com\/","name":"G\u00e1vea News","description":"Veja todas as not\u00edcias sobre o Flamengo: Contrata\u00e7\u00f5es, categorias de base, resultados das partidas, tabela de classifica\u00e7\u00e3o, pr\u00f3ximos jogos!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gaveanews.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/2ec14f73fb96be2caf28f91afb14749d","name":"Equipe G\u00e1vea News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1e1956f1facbffd3f8fa53a326721950116b3b9dc9bd44939c01180fd4a745a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1e1956f1facbffd3f8fa53a326721950116b3b9dc9bd44939c01180fd4a745a9?s=96&d=mm&r=g","caption":"Equipe G\u00e1vea News"}}]}},"_links":{"self":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts\/134063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/comments?post=134063"}],"version-history":[{"count":1,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts\/134063\/revisions"}],"predecessor-version":[{"id":134065,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts\/134063\/revisions\/134065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/media\/132585"}],"wp:attachment":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/media?parent=134063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/categories?post=134063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/tags?post=134063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}