{"id":152492,"date":"2024-07-15T23:05:40","date_gmt":"2024-07-16T02:05:40","guid":{"rendered":"https:\/\/www.gaveanews.com\/?p=152492"},"modified":"2024-07-15T23:05:46","modified_gmt":"2024-07-16T02:05:46","slug":"fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos","status":"publish","type":"post","link":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/","title":{"rendered":"F\u00e1bio Carille ganha dois desfalques para os pr\u00f3ximos jogos do Santos"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-santos-vence-o-ituano-mas-perde-jogadores-importantes-por-lesao\">Santos vence o Ituano, mas perde jogadores importantes por les\u00e3o<\/h2>\n\n\n\n<p>O Santos conquistou uma vit\u00f3ria por 2 a 0 sobre o Ituano, por\u00e9m, o resultado foi ofuscado pelas preocupa\u00e7\u00f5es com les\u00f5es de dois jogadores que s\u00e3o pe\u00e7as chave para o treinador. Durante o jogo, Julio Furch e Aderlan foram obrigados a deixar o campo devido a les\u00f5es, aumentando a incerteza sobre suas participa\u00e7\u00f5es nas pr\u00f3ximas partidas.<\/p>\n\n\n\n<p>Julio Furch, centroavante do time, sofreu uma contus\u00e3o no trap\u00e9zio ainda no primeiro tempo, sendo substitu\u00eddo no intervalo. Enquanto isso, o lateral-direito Aderlan enfrentou um entorse no joelho esquerdo, sendo substitu\u00eddo na etapa final do jogo.<\/p>\n\n\n\n<p>Ambos os jogadores, que haviam recentemente retornado de outras les\u00f5es (Furch de uma pubalgia e Aderlan de uma fratura na m\u00e3o), ser\u00e3o submetidos a exames nesta ter\u00e7a-feira (16) para determinar a gravidade das novas les\u00f5es.<\/p>\n\n\n\n<p>O Santos, atual l\u00edder da S\u00e9rie B, agora se prepara para um confronto decisivo contra o vice-colocado Vila Nova, fora de casa, na 16\u00aa rodada. A partida est\u00e1 marcada para quinta-feira (19), \u00e0s 20h, e a presen\u00e7a de Furch e Aderlan na equipe \u00e9 incerta, dependendo dos resultados dos exames m\u00e9dicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santos vence o Ituano, mas perde jogadores importantes por les\u00e3o O Santos conquistou uma vit\u00f3ria por 2 a 0 sobre o Ituano, por\u00e9m, o resultado foi ofuscado pelas preocupa\u00e7\u00f5es com les\u00f5es de dois jogadores que s\u00e3o pe\u00e7as chave para o treinador. Durante o jogo, Julio Furch e Aderlan foram obrigados a deixar o campo devido [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":152156,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139],"tags":[],"class_list":["post-152492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-santos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>F\u00e1bio Carille ganha dois desfalques para os pr\u00f3ximos jogos do Santos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00e1bio Carille ganha dois desfalques para os pr\u00f3ximos jogos do Santos\" \/>\n<meta property=\"og:description\" content=\"Santos vence o Ituano, mas perde jogadores importantes por les\u00e3o O Santos conquistou uma vit\u00f3ria por 2 a 0 sobre o Ituano, por\u00e9m, o resultado foi ofuscado pelas preocupa\u00e7\u00f5es com les\u00f5es de dois jogadores que s\u00e3o pe\u00e7as chave para o treinador. Durante o jogo, Julio Furch e Aderlan foram obrigados a deixar o campo devido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/\" \/>\n<meta property=\"og:site_name\" content=\"G\u00e1vea News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/gaveaNews\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-16T02:05:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-16T02:05:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/Escudo-do-Santos-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"1056\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Geovanna Thomaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Geovanna Thomaz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/\"},\"author\":{\"name\":\"Geovanna Thomaz\",\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/f42654babcd2b2014a1a65af82b081f1\"},\"headline\":\"F\u00e1bio Carille ganha dois desfalques para os pr\u00f3ximos jogos do Santos\",\"datePublished\":\"2024-07-16T02:05:40+00:00\",\"dateModified\":\"2024-07-16T02:05:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/\"},\"wordCount\":218,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/Escudo-do-Santos-1.webp\",\"articleSection\":[\"Santos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.gaveanews.com\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/\",\"url\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/\",\"name\":\"F\u00e1bio Carille ganha dois desfalques para os pr\u00f3ximos jogos do Santos\",\"isPartOf\":{\"@id\":\"https:\/\/www.gaveanews.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/Escudo-do-Santos-1.webp\",\"datePublished\":\"2024-07-16T02:05:40+00:00\",\"dateModified\":\"2024-07-16T02:05:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/f42654babcd2b2014a1a65af82b081f1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#primaryimage\",\"url\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/Escudo-do-Santos-1.webp\",\"contentUrl\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/Escudo-do-Santos-1.webp\",\"width\":1300,\"height\":1056,\"caption\":\"Escudo do Santos (Foto: Reprodu\u00e7\u00e3o\/Instagram)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.gaveanews.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00e1bio Carille ganha dois desfalques para os pr\u00f3ximos jogos do Santos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gaveanews.com\/#website\",\"url\":\"https:\/\/www.gaveanews.com\/\",\"name\":\"G\u00e1vea News\",\"description\":\"Veja todas as not\u00edcias sobre o Flamengo: Contrata\u00e7\u00f5es, categorias de base, resultados das partidas, tabela de classifica\u00e7\u00e3o, pr\u00f3ximos jogos!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gaveanews.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/f42654babcd2b2014a1a65af82b081f1\",\"name\":\"Geovanna Thomaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4092073255489533afb558984b49b64268c47198af8623cc82a925ae9fb7118a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4092073255489533afb558984b49b64268c47198af8623cc82a925ae9fb7118a?s=96&d=mm&r=g\",\"caption\":\"Geovanna Thomaz\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"F\u00e1bio Carille ganha dois desfalques para os pr\u00f3ximos jogos do Santos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/","og_locale":"pt_BR","og_type":"article","og_title":"F\u00e1bio Carille ganha dois desfalques para os pr\u00f3ximos jogos do Santos","og_description":"Santos vence o Ituano, mas perde jogadores importantes por les\u00e3o O Santos conquistou uma vit\u00f3ria por 2 a 0 sobre o Ituano, por\u00e9m, o resultado foi ofuscado pelas preocupa\u00e7\u00f5es com les\u00f5es de dois jogadores que s\u00e3o pe\u00e7as chave para o treinador. Durante o jogo, Julio Furch e Aderlan foram obrigados a deixar o campo devido [&hellip;]","og_url":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/","og_site_name":"G\u00e1vea News","article_publisher":"https:\/\/facebook.com\/gaveaNews\/","article_published_time":"2024-07-16T02:05:40+00:00","article_modified_time":"2024-07-16T02:05:46+00:00","og_image":[{"width":1300,"height":1056,"url":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/Escudo-do-Santos-1.webp","type":"image\/webp"}],"author":"Geovanna Thomaz","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Geovanna Thomaz","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#article","isPartOf":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/"},"author":{"name":"Geovanna Thomaz","@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/f42654babcd2b2014a1a65af82b081f1"},"headline":"F\u00e1bio Carille ganha dois desfalques para os pr\u00f3ximos jogos do Santos","datePublished":"2024-07-16T02:05:40+00:00","dateModified":"2024-07-16T02:05:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/"},"wordCount":218,"commentCount":0,"image":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/Escudo-do-Santos-1.webp","articleSection":["Santos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.gaveanews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/","url":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/","name":"F\u00e1bio Carille ganha dois desfalques para os pr\u00f3ximos jogos do Santos","isPartOf":{"@id":"https:\/\/www.gaveanews.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#primaryimage"},"image":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/Escudo-do-Santos-1.webp","datePublished":"2024-07-16T02:05:40+00:00","dateModified":"2024-07-16T02:05:46+00:00","author":{"@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/f42654babcd2b2014a1a65af82b081f1"},"breadcrumb":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#primaryimage","url":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/Escudo-do-Santos-1.webp","contentUrl":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/Escudo-do-Santos-1.webp","width":1300,"height":1056,"caption":"Escudo do Santos (Foto: Reprodu\u00e7\u00e3o\/Instagram)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/15\/fabio-carille-ganha-dois-desfalques-para-os-proximos-jogos-do-santos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gaveanews.com\/"},{"@type":"ListItem","position":2,"name":"F\u00e1bio Carille ganha dois desfalques para os pr\u00f3ximos jogos do Santos"}]},{"@type":"WebSite","@id":"https:\/\/www.gaveanews.com\/#website","url":"https:\/\/www.gaveanews.com\/","name":"G\u00e1vea News","description":"Veja todas as not\u00edcias sobre o Flamengo: Contrata\u00e7\u00f5es, categorias de base, resultados das partidas, tabela de classifica\u00e7\u00e3o, pr\u00f3ximos jogos!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gaveanews.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/f42654babcd2b2014a1a65af82b081f1","name":"Geovanna Thomaz","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4092073255489533afb558984b49b64268c47198af8623cc82a925ae9fb7118a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4092073255489533afb558984b49b64268c47198af8623cc82a925ae9fb7118a?s=96&d=mm&r=g","caption":"Geovanna Thomaz"}}]}},"_links":{"self":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts\/152492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/comments?post=152492"}],"version-history":[{"count":1,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts\/152492\/revisions"}],"predecessor-version":[{"id":152496,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts\/152492\/revisions\/152496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/media\/152156"}],"wp:attachment":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/media?parent=152492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/categories?post=152492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/tags?post=152492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}