{"id":152971,"date":"2024-07-18T13:29:58","date_gmt":"2024-07-18T16:29:58","guid":{"rendered":"https:\/\/www.gaveanews.com\/?p=152971"},"modified":"2024-07-18T13:30:02","modified_gmt":"2024-07-18T16:30:02","slug":"santos-contrata-tres-novos-jogadores","status":"publish","type":"post","link":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/","title":{"rendered":"Santos contrata tr\u00eas novos jogadores"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-peixe-anuncia-reforcos-para-a-equipe-sub-20-gabriel-simples-marcelo-torrez-e-ronald-perlaza\">Peixe anuncia refor\u00e7os para a equipe Sub-20: Gabriel Simples, Marcelo T\u00f3rrez e Ronald Perlaza<\/h2>\n\n\n\n<p>O Santos oficializou a contrata\u00e7\u00e3o de tr\u00eas novos jogadores para fortalecer seu elenco sub-20. Gabriel Simples, lateral-direito, Marcelo T\u00f3rrez, zagueiro, e Ronald Perlaza, ponta-esquerda, chegam ao clube para atuar sob o comando do t\u00e9cnico Orlando Ribeiro.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/17\/menino-da-vila-ganha-primeira-oportunidade-no-profissional-do-santos-em-2024\/\">Menino da Vila ganha primeira oportunidade no profissional do Santos em 2024<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/17\/esses-sao-os-jogadores-que-podem-deixar-o-santos-nessa-janela-de-transferencias\/\">Esses s\u00e3o os jogadores que podem deixar o Santos nessa janela de transfer\u00eancias<\/a><\/li>\n<\/ul>\n\n\n\n<p>Gabriel Simples, de 19 anos, foi adquirido junto ao XV de Piracicaba. A equipe do interior paulista confirmou a transfer\u00eancia do jogador em um comunicado nesta ter\u00e7a-feira, revelando que mant\u00e9m um percentual dos direitos econ\u00f4micos do atleta, visando uma futura transfer\u00eancia. O Santos possui a op\u00e7\u00e3o de compra at\u00e9 31 de janeiro de 2025, podendo adquirir uma porcentagem adicional dos direitos de Gabriel.<\/p>\n\n\n\n<p>Marcelo T\u00f3rrez, zagueiro boliviano de 18 anos, tem experi\u00eancia internacional representando a sele\u00e7\u00e3o sub-17 da Bol\u00edvia. O defensor foi titular durante o Sul-Americano da categoria no ano passado, onde marcou um dos tr\u00eas gols de sua equipe na competi\u00e7\u00e3o.<\/p>\n\n\n\n<p>Ronald Perlaza, ponta-esquerda equatoriano de 19 anos, vem do Aucas, do Equador. No in\u00edcio do ano, Perlaza disputou a Copa Conmebol Libertadores da Am\u00e9rica sub-20, onde marcou tr\u00eas gols em quatro jogos, ajudando sua equipe a se destacar na competi\u00e7\u00e3o vencida pelo Flamengo.<\/p>\n\n\n\n<p>Essas contrata\u00e7\u00f5es refletem a continuidade do Santos em investir em jovens promessas sul-americanas. No in\u00edcio do ano, o Peixe j\u00e1 havia trazido o volante venezuelano Nicola Profeta e o meia colombiano Alejandro Villareal, ambos provenientes do Deportivo Cali, da Col\u00f4mbia. Por\u00e9m, devido ao registro como atletas amadores, eles s\u00f3 puderam ser inscritos como profissionais nesta janela de transfer\u00eancias. Ambos j\u00e1 est\u00e3o regularizados, mas ainda n\u00e3o estrearam pelo clube.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peixe anuncia refor\u00e7os para a equipe Sub-20: Gabriel Simples, Marcelo T\u00f3rrez e Ronald Perlaza O Santos oficializou a contrata\u00e7\u00e3o de tr\u00eas novos jogadores para fortalecer seu elenco sub-20. Gabriel Simples, lateral-direito, Marcelo T\u00f3rrez, zagueiro, e Ronald Perlaza, ponta-esquerda, chegam ao clube para atuar sob o comando do t\u00e9cnico Orlando Ribeiro. Gabriel Simples, de 19 anos, [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":148900,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139],"tags":[],"class_list":["post-152971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-santos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Santos contrata tr\u00eas novos jogadores<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santos contrata tr\u00eas novos jogadores\" \/>\n<meta property=\"og:description\" content=\"Peixe anuncia refor\u00e7os para a equipe Sub-20: Gabriel Simples, Marcelo T\u00f3rrez e Ronald Perlaza O Santos oficializou a contrata\u00e7\u00e3o de tr\u00eas novos jogadores para fortalecer seu elenco sub-20. Gabriel Simples, lateral-direito, Marcelo T\u00f3rrez, zagueiro, e Ronald Perlaza, ponta-esquerda, chegam ao clube para atuar sob o comando do t\u00e9cnico Orlando Ribeiro. Gabriel Simples, de 19 anos, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/\" \/>\n<meta property=\"og:site_name\" content=\"G\u00e1vea News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/gaveaNews\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-18T16:29:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-18T16:30:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/53806319831_f435136dc5_3k-1-1536x999.jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"999\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Lucas Barros\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucas Barros\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/\"},\"author\":{\"name\":\"Lucas Barros\",\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/2abf0cfa878f5f899daa5f781e82264c\"},\"headline\":\"Santos contrata tr\u00eas novos jogadores\",\"datePublished\":\"2024-07-18T16:29:58+00:00\",\"dateModified\":\"2024-07-18T16:30:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/\"},\"wordCount\":319,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/53806319831_f435136dc5_3k-1-1536x999.jpg.webp\",\"articleSection\":[\"Santos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.gaveanews.com\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/\",\"url\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/\",\"name\":\"Santos contrata tr\u00eas novos jogadores\",\"isPartOf\":{\"@id\":\"https:\/\/www.gaveanews.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/53806319831_f435136dc5_3k-1-1536x999.jpg.webp\",\"datePublished\":\"2024-07-18T16:29:58+00:00\",\"dateModified\":\"2024-07-18T16:30:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/2abf0cfa878f5f899daa5f781e82264c\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#primaryimage\",\"url\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/53806319831_f435136dc5_3k-1-1536x999.jpg.webp\",\"contentUrl\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/53806319831_f435136dc5_3k-1-1536x999.jpg.webp\",\"width\":1536,\"height\":999,\"caption\":\"Foto: Flickr: Santos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.gaveanews.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santos contrata tr\u00eas novos jogadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gaveanews.com\/#website\",\"url\":\"https:\/\/www.gaveanews.com\/\",\"name\":\"G\u00e1vea News\",\"description\":\"Veja todas as not\u00edcias sobre o Flamengo: Contrata\u00e7\u00f5es, categorias de base, resultados das partidas, tabela de classifica\u00e7\u00e3o, pr\u00f3ximos jogos!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gaveanews.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/2abf0cfa878f5f899daa5f781e82264c\",\"name\":\"Lucas Barros\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/67a6069eba66bf6fd7c80b70e1331baa3dbc3d6df5012d5c22eff29c7d59e0b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/67a6069eba66bf6fd7c80b70e1331baa3dbc3d6df5012d5c22eff29c7d59e0b0?s=96&d=mm&r=g\",\"caption\":\"Lucas Barros\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Santos contrata tr\u00eas novos jogadores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/","og_locale":"pt_BR","og_type":"article","og_title":"Santos contrata tr\u00eas novos jogadores","og_description":"Peixe anuncia refor\u00e7os para a equipe Sub-20: Gabriel Simples, Marcelo T\u00f3rrez e Ronald Perlaza O Santos oficializou a contrata\u00e7\u00e3o de tr\u00eas novos jogadores para fortalecer seu elenco sub-20. Gabriel Simples, lateral-direito, Marcelo T\u00f3rrez, zagueiro, e Ronald Perlaza, ponta-esquerda, chegam ao clube para atuar sob o comando do t\u00e9cnico Orlando Ribeiro. Gabriel Simples, de 19 anos, [&hellip;]","og_url":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/","og_site_name":"G\u00e1vea News","article_publisher":"https:\/\/facebook.com\/gaveaNews\/","article_published_time":"2024-07-18T16:29:58+00:00","article_modified_time":"2024-07-18T16:30:02+00:00","og_image":[{"width":1536,"height":999,"url":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/53806319831_f435136dc5_3k-1-1536x999.jpg.webp","type":"image\/webp"}],"author":"Lucas Barros","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lucas Barros","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#article","isPartOf":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/"},"author":{"name":"Lucas Barros","@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/2abf0cfa878f5f899daa5f781e82264c"},"headline":"Santos contrata tr\u00eas novos jogadores","datePublished":"2024-07-18T16:29:58+00:00","dateModified":"2024-07-18T16:30:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/"},"wordCount":319,"commentCount":0,"image":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/53806319831_f435136dc5_3k-1-1536x999.jpg.webp","articleSection":["Santos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.gaveanews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/","url":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/","name":"Santos contrata tr\u00eas novos jogadores","isPartOf":{"@id":"https:\/\/www.gaveanews.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#primaryimage"},"image":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/53806319831_f435136dc5_3k-1-1536x999.jpg.webp","datePublished":"2024-07-18T16:29:58+00:00","dateModified":"2024-07-18T16:30:02+00:00","author":{"@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/2abf0cfa878f5f899daa5f781e82264c"},"breadcrumb":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#primaryimage","url":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/53806319831_f435136dc5_3k-1-1536x999.jpg.webp","contentUrl":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/53806319831_f435136dc5_3k-1-1536x999.jpg.webp","width":1536,"height":999,"caption":"Foto: Flickr: Santos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gaveanews.com\/index.php\/2024\/07\/18\/santos-contrata-tres-novos-jogadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gaveanews.com\/"},{"@type":"ListItem","position":2,"name":"Santos contrata tr\u00eas novos jogadores"}]},{"@type":"WebSite","@id":"https:\/\/www.gaveanews.com\/#website","url":"https:\/\/www.gaveanews.com\/","name":"G\u00e1vea News","description":"Veja todas as not\u00edcias sobre o Flamengo: Contrata\u00e7\u00f5es, categorias de base, resultados das partidas, tabela de classifica\u00e7\u00e3o, pr\u00f3ximos jogos!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gaveanews.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/2abf0cfa878f5f899daa5f781e82264c","name":"Lucas Barros","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/67a6069eba66bf6fd7c80b70e1331baa3dbc3d6df5012d5c22eff29c7d59e0b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67a6069eba66bf6fd7c80b70e1331baa3dbc3d6df5012d5c22eff29c7d59e0b0?s=96&d=mm&r=g","caption":"Lucas Barros"}}]}},"_links":{"self":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts\/152971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/comments?post=152971"}],"version-history":[{"count":2,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts\/152971\/revisions"}],"predecessor-version":[{"id":153006,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts\/152971\/revisions\/153006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/media\/148900"}],"wp:attachment":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/media?parent=152971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/categories?post=152971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/tags?post=152971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}