{"id":242202,"date":"2025-03-20T06:50:03","date_gmt":"2025-03-20T09:50:03","guid":{"rendered":"https:\/\/www.gaveanews.com\/?p=242202"},"modified":"2025-03-20T06:50:10","modified_gmt":"2025-03-20T09:50:10","slug":"neto-manda-forte-recado-para-lucas-moura-do-sao-paulo","status":"publish","type":"post","link":"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/","title":{"rendered":"Neto manda forte recado para Lucas Moura, do S\u00e3o Paulo"},"content":{"rendered":"\n<p>O apresentador Neto criticou o desempenho de Lucas Moura e Oscar no S\u00e3o Paulo durante o programa &#8220;Os Donos da Bola&#8221; desta quarta-feira (19). Segundo ele, a dupla n\u00e3o tem rendido o esperado em campo, mas ainda assim recebe um tratamento diferenciado por parte da torcida e da imprensa. O ex-jogador destacou principalmente Lucas Moura, que, na vis\u00e3o dele, n\u00e3o justifica o status de \u00eddolo com suas atua\u00e7\u00f5es no Campeonato Paulista.<\/p>\n\n\n\n<p>&#8220;Por que a gente n\u00e3o critica o Lucas Moura? Ele tem s\u00f3 tr\u00eas gols no Paulist\u00e3o. O artilheiro do S\u00e3o Paulo \u00e9 o Andr\u00e9 Silva, com cinco. Como um jogador que ganha uma fortuna, tem o nome que tem e faz s\u00f3 tr\u00eas gols no estadual \u00e9 idolatrado?&#8221;, questionou Neto.<\/p>\n\n\n\n<p>O apresentador tamb\u00e9m criticou a convoca\u00e7\u00e3o de Oscar para a pr\u00e9-lista da sele\u00e7\u00e3o brasileira elaborada por Dorival J\u00fanior. Neto comparou o meia com Raphael Veiga, que, segundo ele, merecia mais a oportunidade.<\/p>\n\n\n\n<p>&#8220;Voc\u00ea pensou no Oscar para estar entre os 50 convocados, mas n\u00e3o pensou no Raphael Veiga? Voc\u00ea est\u00e1 de sacanagem? Est\u00e1 de brincadeira? Sabe quantos gols tem o Oscar? Dois. Pode isso?&#8221;, disparou.<\/p>\n\n\n\n<p>Ainda durante o programa, Neto comparou Lucas e Oscar com Memphis Depay, do Corinthians, que tem sido alvo de cobran\u00e7as, mas tem n\u00fameros superiores aos dos jogadores do S\u00e3o Paulo.<\/p>\n\n\n\n<p>&#8220;Hoje? Entre Memphis, Oscar e Lucas? N\u00e3o tem nem compara\u00e7\u00e3o! O que o Lucas produz? Se ele tivesse feito sete gols, como o Depay, o S\u00e3o Paulo poderia estar na final! Que gol o Lucas ou o Calleri fez no Allianz contra o Palmeiras? Como ia passar?&#8221;, completou.<\/p>\n\n\n\n<p>O S\u00e3o Paulo foi eliminado na semifinal do Campeonato Paulista pelo Palmeiras ap\u00f3s perder por 1 a 0 no Allianz Parque. J\u00e1 Lucas Moura, que retornou ao clube em 2023, soma tr\u00eas gols na competi\u00e7\u00e3o estadual, enquanto Oscar, refor\u00e7o recente da equipe, balan\u00e7ou as redes duas vezes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O apresentador Neto criticou o desempenho de Lucas Moura e Oscar no S\u00e3o Paulo durante o programa &#8220;Os Donos da Bola&#8221; desta quarta-feira (19). Segundo ele, a dupla n\u00e3o tem rendido o esperado em campo, mas ainda assim recebe um tratamento diferenciado por parte da torcida e da imprensa. O ex-jogador destacou principalmente Lucas Moura, [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":143197,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":["post-242202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sao-paulo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Neto manda forte recado para Lucas Moura, do S\u00e3o Paulo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neto manda forte recado para Lucas Moura, do S\u00e3o Paulo\" \/>\n<meta property=\"og:description\" content=\"O apresentador Neto criticou o desempenho de Lucas Moura e Oscar no S\u00e3o Paulo durante o programa &#8220;Os Donos da Bola&#8221; desta quarta-feira (19). Segundo ele, a dupla n\u00e3o tem rendido o esperado em campo, mas ainda assim recebe um tratamento diferenciado por parte da torcida e da imprensa. O ex-jogador destacou principalmente Lucas Moura, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/\" \/>\n<meta property=\"og:site_name\" content=\"G\u00e1vea News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/gaveaNews\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-20T09:50:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-20T09:50:10+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.gaveanews.com\/wp-content\/uploads\/lucas-moura-sao-paulo-2-860x484-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"860\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Geovanna Thomaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Geovanna Thomaz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/\"},\"author\":{\"name\":\"Geovanna Thomaz\",\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/f42654babcd2b2014a1a65af82b081f1\"},\"headline\":\"Neto manda forte recado para Lucas Moura, do S\u00e3o Paulo\",\"datePublished\":\"2025-03-20T09:50:03+00:00\",\"dateModified\":\"2025-03-20T09:50:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/\"},\"wordCount\":343,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/lucas-moura-sao-paulo-2-860x484-1.webp\",\"articleSection\":[\"S\u00e3o Paulo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.gaveanews.com\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/\",\"url\":\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/\",\"name\":\"Neto manda forte recado para Lucas Moura, do S\u00e3o Paulo\",\"isPartOf\":{\"@id\":\"https:\/\/www.gaveanews.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/lucas-moura-sao-paulo-2-860x484-1.webp\",\"datePublished\":\"2025-03-20T09:50:03+00:00\",\"dateModified\":\"2025-03-20T09:50:10+00:00\",\"author\":{\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/f42654babcd2b2014a1a65af82b081f1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#primaryimage\",\"url\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/lucas-moura-sao-paulo-2-860x484-1.webp\",\"contentUrl\":\"https:\/\/www.gaveanews.com\/wp-content\/uploads\/lucas-moura-sao-paulo-2-860x484-1.webp\",\"width\":860,\"height\":484,\"caption\":\"Foto: Divulga\u00e7\u00e3o\/SPFC - Legenda: Lucas deve voltar contra o Barcelona-EQU \/ Jogada10\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.gaveanews.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neto manda forte recado para Lucas Moura, do S\u00e3o Paulo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gaveanews.com\/#website\",\"url\":\"https:\/\/www.gaveanews.com\/\",\"name\":\"G\u00e1vea News\",\"description\":\"Veja todas as not\u00edcias sobre o Flamengo: Contrata\u00e7\u00f5es, categorias de base, resultados das partidas, tabela de classifica\u00e7\u00e3o, pr\u00f3ximos jogos!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gaveanews.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/f42654babcd2b2014a1a65af82b081f1\",\"name\":\"Geovanna Thomaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.gaveanews.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4092073255489533afb558984b49b64268c47198af8623cc82a925ae9fb7118a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4092073255489533afb558984b49b64268c47198af8623cc82a925ae9fb7118a?s=96&d=mm&r=g\",\"caption\":\"Geovanna Thomaz\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Neto manda forte recado para Lucas Moura, do S\u00e3o Paulo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/","og_locale":"pt_BR","og_type":"article","og_title":"Neto manda forte recado para Lucas Moura, do S\u00e3o Paulo","og_description":"O apresentador Neto criticou o desempenho de Lucas Moura e Oscar no S\u00e3o Paulo durante o programa &#8220;Os Donos da Bola&#8221; desta quarta-feira (19). Segundo ele, a dupla n\u00e3o tem rendido o esperado em campo, mas ainda assim recebe um tratamento diferenciado por parte da torcida e da imprensa. O ex-jogador destacou principalmente Lucas Moura, [&hellip;]","og_url":"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/","og_site_name":"G\u00e1vea News","article_publisher":"https:\/\/facebook.com\/gaveaNews\/","article_published_time":"2025-03-20T09:50:03+00:00","article_modified_time":"2025-03-20T09:50:10+00:00","og_image":[{"width":860,"height":484,"url":"http:\/\/www.gaveanews.com\/wp-content\/uploads\/lucas-moura-sao-paulo-2-860x484-1.webp","type":"image\/webp"}],"author":"Geovanna Thomaz","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Geovanna Thomaz","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#article","isPartOf":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/"},"author":{"name":"Geovanna Thomaz","@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/f42654babcd2b2014a1a65af82b081f1"},"headline":"Neto manda forte recado para Lucas Moura, do S\u00e3o Paulo","datePublished":"2025-03-20T09:50:03+00:00","dateModified":"2025-03-20T09:50:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/"},"wordCount":343,"commentCount":0,"image":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/lucas-moura-sao-paulo-2-860x484-1.webp","articleSection":["S\u00e3o Paulo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.gaveanews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/","url":"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/","name":"Neto manda forte recado para Lucas Moura, do S\u00e3o Paulo","isPartOf":{"@id":"https:\/\/www.gaveanews.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#primaryimage"},"image":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/lucas-moura-sao-paulo-2-860x484-1.webp","datePublished":"2025-03-20T09:50:03+00:00","dateModified":"2025-03-20T09:50:10+00:00","author":{"@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/f42654babcd2b2014a1a65af82b081f1"},"breadcrumb":{"@id":"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#primaryimage","url":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/lucas-moura-sao-paulo-2-860x484-1.webp","contentUrl":"https:\/\/www.gaveanews.com\/wp-content\/uploads\/lucas-moura-sao-paulo-2-860x484-1.webp","width":860,"height":484,"caption":"Foto: Divulga\u00e7\u00e3o\/SPFC - Legenda: Lucas deve voltar contra o Barcelona-EQU \/ Jogada10"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gaveanews.com\/index.php\/2025\/03\/20\/neto-manda-forte-recado-para-lucas-moura-do-sao-paulo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gaveanews.com\/"},{"@type":"ListItem","position":2,"name":"Neto manda forte recado para Lucas Moura, do S\u00e3o Paulo"}]},{"@type":"WebSite","@id":"https:\/\/www.gaveanews.com\/#website","url":"https:\/\/www.gaveanews.com\/","name":"G\u00e1vea News","description":"Veja todas as not\u00edcias sobre o Flamengo: Contrata\u00e7\u00f5es, categorias de base, resultados das partidas, tabela de classifica\u00e7\u00e3o, pr\u00f3ximos jogos!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gaveanews.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/f42654babcd2b2014a1a65af82b081f1","name":"Geovanna Thomaz","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.gaveanews.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4092073255489533afb558984b49b64268c47198af8623cc82a925ae9fb7118a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4092073255489533afb558984b49b64268c47198af8623cc82a925ae9fb7118a?s=96&d=mm&r=g","caption":"Geovanna Thomaz"}}]}},"_links":{"self":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts\/242202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/comments?post=242202"}],"version-history":[{"count":1,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts\/242202\/revisions"}],"predecessor-version":[{"id":242203,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/posts\/242202\/revisions\/242203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/media\/143197"}],"wp:attachment":[{"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/media?parent=242202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/categories?post=242202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gaveanews.com\/index.php\/wp-json\/wp\/v2\/tags?post=242202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}